{"id":29251,"date":"2026-03-04T08:15:04","date_gmt":"2026-03-04T08:15:04","guid":{"rendered":"https:\/\/zeitblick.at\/?p=29251"},"modified":"2026-03-04T08:15:42","modified_gmt":"2026-03-04T08:15:42","slug":"in-wien-beruhigt-sich-die-lage-in-der-soez-partei-nicht-offener-brief-von-ibrahim-koc","status":"publish","type":"post","link":"https:\/\/zeitblick.at\/index.php\/2026\/03\/04\/in-wien-beruhigt-sich-die-lage-in-der-soez-partei-nicht-offener-brief-von-ibrahim-koc\/","title":{"rendered":"In Wien beruhigt sich die Lage in der S\u00d6Z-Partei nicht: Offener Brief von \u0130brahim Ko\u00e7"},"content":{"rendered":"\n<p>In der Wiener Politik sorgen die j\u00fcngsten Entwicklungen rund um die Partei <strong>S\u00d6Z \u2013 Soziales \u00d6sterreich der Zukunft<\/strong> weiterhin f\u00fcr Diskussionen. Nach den letzten Wahlen wird innerhalb und au\u00dferhalb der Partei verst\u00e4rkt \u00fcber die politische Entwicklung und die Wahlergebnisse debattiert. Trotz finanzieller Unterst\u00fctzung aus \u00f6ffentlichen Mitteln in H\u00f6he von <strong>421.608 Euro in den vergangenen f\u00fcnf Jahren<\/strong> musste die Partei einen deutlichen Stimmenverlust hinnehmen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rund 3.000 Stimmen weniger in f\u00fcnf Jahren<\/h3>\n\n\n\n<p>Ein Blick auf die Ergebnisse der <strong>Wiener Landtags- und Gemeinderatswahlen<\/strong> zeigt, dass die S\u00d6Z-Partei zwischen <strong>2020 und 2025<\/strong> Stimmen verloren hat.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Wien-Wahl 2020:<\/strong> 8.742 Stimmen (<strong>1,20 %<\/strong>)<\/li>\n\n\n\n<li><strong>Wien-Wahl 2025:<\/strong> 5.737 Stimmen (<strong>0,84 %<\/strong>)<\/li>\n<\/ul>\n\n\n\n<p>Damit verlor die Partei insgesamt <strong>3.005 Stimmen<\/strong>, w\u00e4hrend der Stimmenanteil von <strong>1,20 Prozent auf 0,84 Prozent<\/strong> zur\u00fcckging. Der R\u00fcckgang der Stimmen trotz erheblicher \u00f6ffentlicher F\u00f6rderungen hat in politischen Kreisen und innerhalb der Partei neue Diskussionen \u00fcber die strategische Ausrichtung und die F\u00fchrung ausgel\u00f6st.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Offener Brief aus den eigenen Reihen<\/h3>\n\n\n\n<p>Die Debatte beschr\u00e4nkt sich jedoch nicht nur auf die Wahlergebnisse. <strong>\u0130brahim Ko\u00e7<\/strong>, der nach eigenen Angaben jahrelang ohne pers\u00f6nliche Interessen f\u00fcr die Partei gearbeitet hat, ver\u00f6ffentlichte \u00fcber seine Social-Media-Kan\u00e4le einen <strong>offenen Brief an die Parteif\u00fchrung<\/strong>.<\/p>\n\n\n\n<p>Besonders bemerkenswert ist, dass <strong>Ko\u00e7 bei den Wiener Wahlen 2025 nicht auf die Kandidatenliste gesetzt wurde<\/strong>, seine <strong>Parteimitgliedschaft jedoch weiterhin besteht<\/strong>. Trotz dieser Situation \u00e4u\u00dfert er \u00f6ffentlich Kritik an internen Abl\u00e4ufen innerhalb der Partei.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Warum wurde keine Generalversammlung abgehalten?<\/h3>\n\n\n\n<p>In seinem offenen Brief stellt Ko\u00e7 eine zentrale Frage: <strong>Warum wurde keine Generalversammlung abgehalten<\/strong>, obwohl diese laut Parteistatuten verpflichtend vorgesehen ist?<\/p>\n\n\n\n<p>Nach seiner Darstellung sei die <strong>Generalversammlung das h\u00f6chste Organ der Partei<\/strong>, in dem der Wille der Mitglieder erneuert und die demokratische Legitimation sichergestellt werde. Dass eine solche Versammlung trotz der aktuellen Entwicklungen nicht durchgef\u00fchrt wurde, werfe aus seiner Sicht grundlegende Fragen zur innerparteilichen Demokratie auf.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vorw\u00fcrfe \u00fcber Ver\u00e4nderungen im Parteivorstand<\/h3>\n\n\n\n<p>Ein weiterer Punkt in Ko\u00e7\u2019 Erkl\u00e4rung betrifft m\u00f6gliche Ver\u00e4nderungen innerhalb der Parteif\u00fchrung. Laut Ko\u00e7 habe <strong>Nur Can vor den Wiener Wahlen \u00f6ffentlich \u00fcber ihre Social-Media-Kan\u00e4le erkl\u00e4rt, dass sie sowohl aus der Parteif\u00fchrung als auch aus der Partei austritt<\/strong>.<\/p>\n\n\n\n<p>Dar\u00fcber hinaus habe ein weiteres Mitglied des Parteivorstands ihm schriftlich \u00fcber <strong>WhatsApp mitgeteilt<\/strong>, dass es sp\u00e4testens <strong>seit dem 1. August 2025 keine Verbindung mehr zur Partei habe<\/strong>. Ob diese Erkl\u00e4rung jedoch offiziell als R\u00fccktritt an die Partei \u00fcbermittelt und registriert wurde, sei nach seinen Angaben bis heute unklar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Offene Fragen an die Parteif\u00fchrung<\/h3>\n\n\n\n<p>Vor diesem Hintergrund stellt Ko\u00e7 mehrere Fragen an die Parteif\u00fchrung:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Warum wurde trotz \u00f6ffentlich erkl\u00e4rter R\u00fccktritte im Vorstand <strong>keine Generalversammlung gem\u00e4\u00df den Parteistatuten einberufen<\/strong>?<\/li>\n\n\n\n<li>Warum wurde <strong>kein demokratischer Erneuerungsprozess<\/strong> gestartet, obwohl einzelne Personen erkl\u00e4rt haben, dass sie keine Verbindung mehr zur Partei haben?<\/li>\n\n\n\n<li>Falls es Unterschiede zwischen der <strong>offiziellen und der tats\u00e4chlichen Situation<\/strong> innerhalb der Parteistrukturen gibt, warum werden diese nicht transparent erkl\u00e4rt?<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">\u201eTransparenz und Rechenschaftspflicht sind grundlegend\u201c<\/h3>\n\n\n\n<p>Am Ende seines offenen Briefes betont Ko\u00e7, dass <strong>Transparenz und Rechenschaftspflicht grundlegende Prinzipien jeder politischen Partei<\/strong> seien. Aus seiner Sicht m\u00fcsse die Parteif\u00fchrung zu den aufgeworfenen Fragen Stellung nehmen und f\u00fcr Klarheit sorgen.<\/p>\n\n\n\n<p>Der Stimmenverlust bei den Wahlen sowie die Kritik aus den eigenen Reihen zeigen, dass die Diskussionen innerhalb der <strong>S\u00d6Z-Partei in Wien<\/strong> noch nicht beendet sind und auch in den kommenden Monaten weitergef\u00fchrt werden d\u00fcrften.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der Wiener Politik sorgen die j\u00fcngsten Entwicklungen rund um die Partei S\u00d6Z \u2013 Soziales \u00d6sterreich der Zukunft weiterhin f\u00fcr Diskussionen. Nach den letzten Wahlen wird innerhalb und au\u00dferhalb der Partei verst\u00e4rkt \u00fcber die politische Entwicklung und die Wahlergebnisse debattiert. Trotz finanzieller Unterst\u00fctzung aus \u00f6ffentlichen Mitteln in H\u00f6he von 421.608 Euro in den vergangenen f\u00fcnf<\/p>\n","protected":false},"author":1,"featured_media":29252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91,67,1],"tags":[815,813,486,817,812,229,814,816],"class_list":{"0":"post-29251","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-innenpolitik-at","8":"category-at","9":"category-verkehr","10":"tag-hakan-goerdue","11":"tag-ibrahim-koc","12":"tag-oesterreich-politik","13":"tag-parteikrise","14":"tag-soez-partei","15":"tag-wien","16":"tag-wien-wahl-2025","17":"tag-wiener-politik"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/posts\/29251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/comments?post=29251"}],"version-history":[{"count":1,"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/posts\/29251\/revisions"}],"predecessor-version":[{"id":29253,"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/posts\/29251\/revisions\/29253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/media\/29252"}],"wp:attachment":[{"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/media?parent=29251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/categories?post=29251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zeitblick.at\/index.php\/wp-json\/wp\/v2\/tags?post=29251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}